{"id":39142,"date":"2024-01-22T19:22:42","date_gmt":"2024-01-22T19:22:42","guid":{"rendered":"http:\/\/www.ccof.org\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/"},"modified":"2024-04-18T18:24:50","modified_gmt":"2024-04-18T18:24:50","slug":"ccof-receives-3-million-grant-from-usda-for-organic-market-development","status":"publish","type":"post","link":"https:\/\/ccof.org\/es\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/","title":{"rendered":"CCOF recibe una subvenci\u00f3n de $3 millones del USDA para el desarrollo del mercado org\u00e1nico"},"content":{"rendered":"<div style=\"text-align: center;\">&#xD;       <\/p>\n<p><em><strong>Con nueva financiaci\u00f3n, CCOF educar\u00e1 a los consumidores y apoyar\u00e1 a los productores org\u00e1nicos <\/strong><\/em>&#xA0;<\/p>\n<p>&#xD;       <\/p><\/div>\n<p>&#xD;       &#xD;       <\/p>\n<p><strong>(22 de enero de 2024) Santa Cruz, CA<\/strong> - Es un honor para el CCOF recibir $3 millones del USDA, <a       href=\"https:\/\/www.ams.usda.gov\/press-release\/more-20000-domestic-producers-benefit-usda-awards-providing-organic-market\">que ha concedido $9,75 millones de<\/a> a 10 proyectos a trav\u00e9s de su programa de Subvenciones para el Desarrollo de Mercados Org\u00e1nicos (OMDG). Esta es la primera ronda de financiaci\u00f3n concedida a trav\u00e9s del programa de Subvenciones para el Desarrollo de Mercados Org\u00e1nicos, cuyo objetivo es abrir y ampliar nuevas fuentes de ingresos para la industria org\u00e1nica y crear m\u00e1s oportunidades para los agricultores estadounidenses.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>\"Solicitamos financiaci\u00f3n para poder ofrecer m\u00e1s apoyo a los productores org\u00e1nicos a la hora de llegar a los compradores y educar a los consumidores\", afirma la directora general de CCOF, Kelly Damewood. \"Esta subvenci\u00f3n permite a CCOF aumentar la confianza del p\u00fablico en la etiqueta org\u00e1nica al tiempo que eleva las oportunidades de mercado para los productores org\u00e1nicos desatendidos.\"<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>Este a\u00f1o, el CCOF se embarcar\u00e1 en una campa\u00f1a a gran escala de tres a\u00f1os de duraci\u00f3n para mejorar y ampliar el acceso al mercado de los peque\u00f1os agricultores ecol\u00f3gicos desatendidos. Con los recursos de la subvenci\u00f3n del USDA, el CCOF pondr\u00e1 en marcha una campa\u00f1a de marketing que abordar\u00e1 dos obst\u00e1culos clave que restringen el crecimiento de las ventas de productos org\u00e1nicos: la falta de claridad de los consumidores sobre lo que significa org\u00e1nico y su falta de confianza en el sello. El CCOF crear\u00e1 v\u00edas de mercado para los productores ecol\u00f3gicos peque\u00f1os y desatendidos, poni\u00e9ndolos en contacto con compradores que buscan activamente abastecerse de sus productos, adem\u00e1s de educar a los agricultores sobre c\u00f3mo hablar a los consumidores y compradores acerca de lo org\u00e1nico y proporcionarles las herramientas para hacerlo. CCOF ser\u00e1 la primera organizaci\u00f3n en promover lo org\u00e1nico a trav\u00e9s de la televisi\u00f3n nacional y la publicidad digital.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>Los resultados esperados de este proyecto son que los consumidores y compradores adquieran conocimientos sobre los productos org\u00e1nicos y que los productores peque\u00f1os y desatendidos aumenten la producci\u00f3n org\u00e1nica para satisfacer el aumento de la demanda resultante a trav\u00e9s de los canales del mercado directo y las transacciones comerciales de los compradores.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>El CCOF hace extensiva su merecida felicitaci\u00f3n a los dem\u00e1s beneficiarios de esta subvenci\u00f3n. Los proyectos premiados apoyan las oportunidades de mercado de alimentos y productos agr\u00edcolas de EE.UU., al tiempo que aumentan el acceso de los consumidores a alimentos frescos y saludables. Estos proyectos apoyar\u00e1n a los productores org\u00e1nicos y promover\u00e1n los objetivos del USDA para desarrollar m\u00e1s y mejores mercados, hacer crecer un sistema alimentario diverso y equitativo, y aumentar las pr\u00e1cticas agr\u00edcolas clim\u00e1ticamente inteligentes. El CCOF y los dem\u00e1s beneficiarios est\u00e1n dando un gran paso hacia un futuro en el que lo org\u00e1nico sea la norma.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>&#xD;       <u><em>Sobre CCOF<\/em><\/u><\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p><em><a href=\"https:\/\/ccof.org\/es\/\">CCOF<\/a> promueve la agricultura org\u00e1nica para un mundo sano. Abogamos en nombre de nuestros miembros por pol\u00edticas org\u00e1nicas, apoyamos el crecimiento de la agricultura org\u00e1nica a trav\u00e9s de la educaci\u00f3n y las subvenciones, y proporcionamos certificaci\u00f3n org\u00e1nica personal y accesible.<\/em><\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p><em>CCOF es una organizaci\u00f3n sin \u00e1nimo de lucro regida por las personas que cultivan y elaboran nuestros alimentos. Fundada en California hace m\u00e1s de 50 a\u00f1os, hoy nuestras ra\u00edces se extienden por toda Norteam\u00e9rica y nuestra presencia es reconocida internacionalmente. Contamos con el apoyo de una familia org\u00e1nica de agricultores, ganaderos, procesadores, minoristas, consumidores y responsables pol\u00edticos. Juntos, trabajamos para hacer realidad un futuro en el que lo org\u00e1nico sea la norma.<br \/>Para m\u00e1s informaci\u00f3n sobre el CCOF, visite <a       href=\"https:\/\/ccof.org\/es\/\">www.ccof.org<\/a>.<\/em><br \/>&#xD;       &#xA0;<\/p>\n<p>&#xD;<\/p>","protected":false},"excerpt":{"rendered":"<p>Con nuevos fondos, CCOF educar\u00e1 a los consumidores y apoyar\u00e1 a los productores org\u00e1nicos ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[114],"class_list":["post-39142","post","type-post","status-publish","format-standard","hentry","category-press-release","language-english","advocacy_campaigns-farm-processor-viability","advocacy_campaigns-market-integrity-development"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CCOF Receives $3 Million Grant from USDA for Organic Market Development - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccof.org\/es\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CCOF Receives $3 Million Grant from USDA for Organic Market Development - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"&#xD; With New Funding, CCOF Will Educate Consumers and Support Organic Producers &#xA0; &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccof.org\/es\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T19:22:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T18:24:50+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"CCOF Receives $3 Million Grant from USDA for Organic Market Development\",\"datePublished\":\"2024-01-22T19:22:42+00:00\",\"dateModified\":\"2024-04-18T18:24:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Press Release\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/\",\"url\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/\",\"name\":\"CCOF Receives $3 Million Grant from USDA for Organic Market Development - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2024-01-22T19:22:42+00:00\",\"dateModified\":\"2024-04-18T18:24:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CCOF Receives $3 Million Grant from USDA for Organic Market Development\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CCOF recibe una subvenci\u00f3n de $3 millones del USDA para el desarrollo del mercado ecol\u00f3gico - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccof.org\/es\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/","og_locale":"es_MX","og_type":"article","og_title":"CCOF Receives $3 Million Grant from USDA for Organic Market Development - CCOF.org","og_description":"&#xD; With New Funding, CCOF Will Educate Consumers and Support Organic Producers &#xA0; &hellip;","og_url":"https:\/\/ccof.org\/es\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2024-01-22T19:22:42+00:00","article_modified_time":"2024-04-18T18:24:50+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/#article","isPartOf":{"@id":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"CCOF Receives $3 Million Grant from USDA for Organic Market Development","datePublished":"2024-01-22T19:22:42+00:00","dateModified":"2024-04-18T18:24:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Press Release"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/","url":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/","name":"CCOF recibe una subvenci\u00f3n de $3 millones del USDA para el desarrollo del mercado ecol\u00f3gico - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2024-01-22T19:22:42+00:00","dateModified":"2024-04-18T18:24:50+00:00","breadcrumb":{"@id":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ccof.org\/news\/ccof-receives-3-million-grant-from-usda-for-organic-market-development\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"CCOF Receives $3 Million Grant from USDA for Organic Market Development"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/39142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/comments?post=39142"}],"version-history":[{"count":1,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/39142\/revisions"}],"predecessor-version":[{"id":41044,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/39142\/revisions\/41044"}],"wp:attachment":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/media?parent=39142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/categories?post=39142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}