{"id":39106,"date":"2013-07-11T23:29:06","date_gmt":"2013-07-11T23:29:06","guid":{"rendered":"http:\/\/www.ccof.org\/?p=39106"},"modified":"2024-04-18T18:24:41","modified_gmt":"2024-04-18T18:24:41","slug":"ccof-once-again-tops-list-of-nop-organic-certifiers","status":"publish","type":"post","link":"https:\/\/ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/","title":{"rendered":"CCOF vuelve a encabezar la lista de certificadoras org\u00e1nicas NOP"},"content":{"rendered":"<div class=\"field field-name-body field-type-text-with-summary       field-label-hidden\">&#xD;       <\/p>\n<div class=\"field-items\">&#xD;       <\/p>\n<div class=\"field-item even\">&#xD;       <\/p>\n<h3 align=\"center\" style=\"color:#b86339;fontfamily:soho       std,arial,helvetica;fontweight:500;\"><strong>El Programa Nacional Org\u00e1nico (NOP) del USDA publica una lista actualizada de operaciones org\u00e1nicas certificadas<\/strong><\/h3>\n<p>&#xD;       &#xD;       <\/p>\n<p><strong>(4 de abril de 2013) Santa Cruz, CA <\/strong>- Las cifras publicadas recientemente indican que los Servicios de Certificaci\u00f3n de CCOF siguen siendo el mayor certificador de productos org\u00e1nicos del mundo del Programa Nacional Org\u00e1nico (NOP) del USDA. CCOF certifica 2.346 operaciones, dando servicio a 14% de operaciones org\u00e1nicas certificadas por el USDA. La certificadora californiana gan\u00f3 1% de cuota de mercado en el \u00faltimo a\u00f1o, m\u00e1s que cualquier otra certificadora org\u00e1nica del pa\u00eds.       Adem\u00e1s del principal programa de certificaci\u00f3n org\u00e1nica, la organizaci\u00f3n sin \u00e1nimo de lucro CCOF (California Certified Organic Famers) se encuentra entre los defensores m\u00e1s influyentes de la naci\u00f3n en nombre de lo org\u00e1nico.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p style=\"text-align: center;\"><u>Comparaci\u00f3n de datos de certificadoras org\u00e1nicas acreditadas por el USDA en 2012<\/u>*<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" data-entity-type=\"file\"       data-entity-uuid=\"969e8376-d38c-478d-b9b7-8947ad03aa57\" height=\"425\"       src=\"http:\/\/www.ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png\"       width=\"650\" \/><\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>A finales de 2012, CCOF se convirti\u00f3 en la primera certificadora en ofrecer acceso en l\u00ednea en tiempo real a los Planes de Sistemas Org\u00e1nicos (PSO). La organizaci\u00f3n tambi\u00e9n ha triplicado el servicio telef\u00f3nico de primera l\u00ednea y se ha comprometido con el NOP en las barreras a la certificaci\u00f3n y la reducci\u00f3n del papeleo. Encontrar\u00e1 m\u00e1s informaci\u00f3n en el sitio web de CCOF. <em>Del campo al foro<\/em> blog en <a href=\"https:\/\/ccof.org\/es\/blog\/\" target=\"_blank\" rel=\"noopener\">www.ccof.org\/blog<\/a>.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p align=\"left\">\"2012 fue un a\u00f1o emocionante para CCOF\", dijo el Director de Certificaci\u00f3n de CCOF, Jake Lewin. \"Hemos trabajado duro para ofrecer servicios nuevos e innovadores a los clientes, y creemos que estos beneficios han tenido un impacto positivo en la retenci\u00f3n y adquisici\u00f3n de clientes. Tenemos grandes planes para 2013\".<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>Puede encontrar una lista de operaciones certificadas por el Programa Nacional Org\u00e1nico (NOP) en       <a href=\"http:\/\/apps.ams.usda.gov\/nop\/\" target=\"_blank\" rel=\"noopener\">apps.ams.usda.gov\/nop\/<\/a>.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>&#xA0;<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p>*Las cifras anteriores se han elaborado a partir de datos disponibles en <a href=\"http:\/\/apps.ams.usda.gov\/nop\/\" target=\"_blank\" rel=\"noopener\">apps.ams.usda.gov\/nop\/<\/a>.<\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p><em><u>Sobre CCOF<\/u><\/em><\/p>\n<p>&#xD;       &#xD;       <\/p>\n<p><em>CCOF (California Certified Organic Farmers), una organizaci\u00f3n sin \u00e1nimo de lucro, fue fundada en 1973 y es una de las mayores y m\u00e1s antiguas agencias de certificaci\u00f3n org\u00e1nica del pa\u00eds. CCOF certifica, educa, defiende y promueve lo org\u00e1nico:<\/em><\/p>\n<p>&#xD;       &#xD;       <\/p>\n<ul>&#xD;       <\/p>\n<li><em>Un programa de certificaci\u00f3n org\u00e1nica de primera clase para productores, procesadores, distribuidores y minoristas.<\/em><\/li>\n<p>&#xD;       <\/p>\n<li><em>Programas para aumentar el conocimiento y la demanda de productos org\u00e1nicos certificados y para ampliar el apoyo p\u00fablico a la agricultura org\u00e1nica.<\/em><\/li>\n<p>&#xD;       <\/p>\n<li><em>Defensa de pol\u00edticas gubernamentales que protejan y fomenten la agricultura org\u00e1nica.<\/em><\/li>\n<p>&#xD;       <\/ul>\n<p>&#xD;       &#xD;       <\/p>\n<p><em>El CCOF certifica m\u00e1s de 2.500 operaciones org\u00e1nicas en 33 estados y tres pa\u00edses extranjeros y atiende a m\u00e1s de 240 miembros de apoyo -consumidores, proveedores, empresas y particulares- interesados en respaldar su labor.<\/em><em>.<\/em><\/p>\n<p>&#xD;       <\/p><\/div>\n<p>&#xD;       <\/p><\/div>\n<p>&#xD;       <\/p><\/div>\n<p>&#xD;       &#xD;       <\/p>\n<p>&#xA0;<\/p>\n<p>&#xD;<\/p>","protected":false},"excerpt":{"rendered":"<p>El Programa Nacional Org\u00e1nico (NOP) del USDA publica una lista actualizada de ...<\/p>","protected":false},"author":1,"featured_media":39107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[114],"class_list":["post-39106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-release","language-english","certification_topics-other-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CCOF Once Again Tops List of NOP Organic Certifiers - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CCOF Once Again Tops List of NOP Organic Certifiers - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"&#xD; &#xD; &#xD; USDA National Organic Program (NOP) Releases Updated List of Certified &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-11T23:29:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T18:24:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"CCOF Once Again Tops List of NOP Organic Certifiers\",\"datePublished\":\"2013-07-11T23:29:06+00:00\",\"dateModified\":\"2024-04-18T18:24:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/\"},\"wordCount\":395,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png\",\"articleSection\":[\"Press Release\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/\",\"name\":\"CCOF Once Again Tops List of NOP Organic Certifiers - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png\",\"datePublished\":\"2013-07-11T23:29:06+00:00\",\"dateModified\":\"2024-04-18T18:24:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png\",\"contentUrl\":\"https:\\\/\\\/ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png\",\"width\":650,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/ccof-once-again-tops-list-of-nop-organic-certifiers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CCOF Once Again Tops List of NOP Organic Certifiers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CCOF encabeza de nuevo la lista de certificadoras ecol\u00f3gicas NOP - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/","og_locale":"es_MX","og_type":"article","og_title":"CCOF Once Again Tops List of NOP Organic Certifiers - CCOF.org","og_description":"&#xD; &#xD; &#xD; USDA National Organic Program (NOP) Releases Updated List of Certified &hellip;","og_url":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2013-07-11T23:29:06+00:00","article_modified_time":"2024-04-18T18:24:41+00:00","og_image":[{"width":650,"height":425,"url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#article","isPartOf":{"@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"CCOF Once Again Tops List of NOP Organic Certifiers","datePublished":"2013-07-11T23:29:06+00:00","dateModified":"2024-04-18T18:24:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/"},"wordCount":395,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"image":{"@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#primaryimage"},"thumbnailUrl":"https:\/\/ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png","articleSection":["Press Release"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/","url":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/","name":"CCOF encabeza de nuevo la lista de certificadoras ecol\u00f3gicas NOP - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#primaryimage"},"image":{"@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#primaryimage"},"thumbnailUrl":"https:\/\/ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png","datePublished":"2013-07-11T23:29:06+00:00","dateModified":"2024-04-18T18:24:41+00:00","breadcrumb":{"@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#primaryimage","url":"https:\/\/ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png","contentUrl":"https:\/\/ccof.org\/wp-content\/uploads\/2024\/04\/2012-USDA-Accredited-Organic-Certifier-Data-Comparison.png","width":650,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccof.org\/es\/news\/ccof-once-again-tops-list-of-nop-organic-certifiers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"CCOF Once Again Tops List of NOP Organic Certifiers"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/39106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/comments?post=39106"}],"version-history":[{"count":1,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/39106\/revisions"}],"predecessor-version":[{"id":41065,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/39106\/revisions\/41065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/media\/39107"}],"wp:attachment":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/media?parent=39106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/categories?post=39106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}