{"id":33762,"date":"2022-04-04T20:49:00","date_gmt":"2022-04-04T20:49:00","guid":{"rendered":"https:\/\/www.ccof.org\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/"},"modified":"2024-04-23T21:08:38","modified_gmt":"2024-04-23T21:08:38","slug":"california-organic-processed-product-sales-soar-to-34-5-billion-in-2021","status":"publish","type":"post","link":"https:\/\/ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/","title":{"rendered":"Las ventas de productos org\u00e1nicos transformados en California se disparan hasta los 1.300 millones en 2021"},"content":{"rendered":"<p>A <a       href=\"chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/viewer.html?pdfurl=https%3A%2F%2Fwww.cdph.ca.gov%2FPrograms%2FCEH%2FDFDCS%2FCDPH%2520Document%2520Library%2FFDB%2FFoodSafetyProgram%2FOrganic%2FCDPHOrganicReport2022.pdf\">nuevo informe<\/a> emitido por el Programa Org\u00e1nico Estatal del Departamento de Salud P\u00fablica de California muestra un crecimiento asombroso de las ventas de productos org\u00e1nicos entre 2020 y 2021, de 1.400 millones de euros a 1.300 millones de euros.<\/p>\n<p>La mediana de las ventas brutas anuales tambi\u00e9n se duplic\u00f3 con creces, pasando de 1.470.000 PTT en 2020 a 1.450.000 PTT en 2021. El an\u00e1lisis de los solicitantes de registro por volumen de ventas revela que el n\u00famero de solicitantes de registro que pagan la tasa m\u00e1s alta -700 para empresas con ventas brutas superiores a $2,5 millones- aument\u00f3 de 603 en 2020 a 690 en 2021.<\/p>\n<p>Al mismo tiempo, el n\u00famero de inscritos org\u00e1nicos en el Programa Estatal de Agricultura Ecol\u00f3gica disminuy\u00f3 de 2.777 en 2020 a 2.606 en 2021.\u00a0<\/p>\n<p>Esta nueva informaci\u00f3n es oportuna ya que CCOF persigue la legislaci\u00f3n para hacer los cambios necesarios en la ley que regula los procesadores org\u00e1nicos en California.<\/p>\n<p>El proyecto de ley, <a       href=\"https:\/\/leginfo.legislature.ca.gov\/faces\/billTextClient.xhtml?bill_id=202120220AB1870\">AB 1870<\/a>El proyecto de ley, cuyo autor es el asamble\u00edsta Mark Stone y co-autor por el asamble\u00edsta Marc Levine y el senador John Laird. Requerir\u00e1 que el CDPH<\/p>\n<ol><\/p>\n<li>desarrollar una opci\u00f3n de inscripci\u00f3n y pago en l\u00ednea para el Programa Org\u00e1nico Estatal,\u00a0<\/li>\n<figure class=\"content-image\"><\/figure>\n<li>reducir el n\u00famero de formularios necesarios,\u00a0<\/li>\n<figure class=\"content-image\"><\/figure>\n<li>Aportar transparencia a los costes de los programas informando sobre gastos e ingresos,\u00a0<\/li>\n<figure class=\"content-image\"><\/figure>\n<li>Eliminar a los malos agentes del sector lo antes posible, creando un procedimiento para aclarar las denuncias que no puedan resolverse en el plazo de 90 d\u00edas que exige la ley.<\/li>\n<p><\/ol>\n<p>El AB 1870 est\u00e1 programado para ser escuchado en el Comit\u00e9 de Agricultura de la Asamblea el 27 de abril. El CCOF sigue recogiendo firmas para una carta de apoyo.\u00a0<\/p>\n<p>Por favor, \u00fanase a CCOF para demostrar que la comunidad org\u00e1nica de California est\u00e1 unida para apoyar un Programa Org\u00e1nico Estatal actualizado.       Para firmar la carta de apoyo, env\u00ede el logotipo de su empresa y una firma electr\u00f3nica a Jane Sooby, Especialista Senior en Pol\u00edtica y Divulgaci\u00f3n, antes del 8 de abril en <a       href=\"\/es\/jsooby@ccof.org\/\">jsooby@ccof.org<\/a>\u00a0<\/p>\n<p>No dude en ponerse en contacto con ella para obtener m\u00e1s informaci\u00f3n por correo electr\u00f3nico o por tel\u00e9fono en el (831) 425-7205.<\/p>\n<p>\u00a0<\/p>\n<figure class=\"content-image\"><\/figure>","protected":false},"excerpt":{"rendered":"<p>Un nuevo informe publicado por el Departamento de Salud P\u00fablica de California ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[111],"class_list":["post-33762","post","type-post","status-publish","format-standard","hentry","category-foundation-news","language-english","foundation_topics-education"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>California Organic Processed Product Sales Soar to $34.5 Billion in 2021 - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"California Organic Processed Product Sales Soar to $34.5 Billion in 2021 - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"A new report issued by the California Department of Public Health\u2019s State Organic &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T20:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T21:08:38+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"California Organic Processed Product Sales Soar to $34.5 Billion in 2021\",\"datePublished\":\"2022-04-04T20:49:00+00:00\",\"dateModified\":\"2024-04-23T21:08:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Foundation News\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/\",\"name\":\"California Organic Processed Product Sales Soar to $34.5 Billion in 2021 - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2022-04-04T20:49:00+00:00\",\"dateModified\":\"2024-04-23T21:08:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"California Organic Processed Product Sales Soar to $34.5 Billion in 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ventas de productos ecol\u00f3gicos procesados en California se disparan hasta los $34.500 millones en 2021 - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/","og_locale":"es_MX","og_type":"article","og_title":"California Organic Processed Product Sales Soar to $34.5 Billion in 2021 - CCOF.org","og_description":"A new report issued by the California Department of Public Health\u2019s State Organic &hellip;","og_url":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2022-04-04T20:49:00+00:00","article_modified_time":"2024-04-23T21:08:38+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/#article","isPartOf":{"@id":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"California Organic Processed Product Sales Soar to $34.5 Billion in 2021","datePublished":"2022-04-04T20:49:00+00:00","dateModified":"2024-04-23T21:08:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Foundation News"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/","url":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/","name":"Las ventas de productos ecol\u00f3gicos procesados en California se disparan hasta los $34.500 millones en 2021 - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2022-04-04T20:49:00+00:00","dateModified":"2024-04-23T21:08:38+00:00","breadcrumb":{"@id":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccof.org\/es\/news\/california-organic-processed-product-sales-soar-to-34-5-billion-in-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"California Organic Processed Product Sales Soar to $34.5 Billion in 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/33762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/comments?post=33762"}],"version-history":[{"count":3,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/33762\/revisions"}],"predecessor-version":[{"id":40967,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/33762\/revisions\/40967"}],"wp:attachment":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/media?parent=33762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/categories?post=33762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}