{"id":33683,"date":"2021-11-02T22:46:17","date_gmt":"2021-11-02T22:46:17","guid":{"rendered":"https:\/\/www.ccof.org\/a-tale-of-two-farms-dedicated-to-the-same-cause\/"},"modified":"2024-04-23T21:08:20","modified_gmt":"2024-04-23T21:08:20","slug":"a-tale-of-two-farms-dedicated-to-the-same-cause","status":"publish","type":"post","link":"https:\/\/ccof.org\/es\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/","title":{"rendered":"Historia de dos granjas dedicadas a la misma causa"},"content":{"rendered":"<p>Dos explotaciones cann\u00e1bicas californianas han marcado un nuevo hito en el sector del cannabis y han sido certificadas como las primeras explotaciones de cannabis \"comparables a las org\u00e1nicas\" del Estado y de los Estados Unidos, por <a href=\"https:\/\/ccof.org\/es\/\">CCOF<\/a>       (Agricultores Org\u00e1nicos Certificados de California). OCal es un nuevo programa de certificaci\u00f3n del Departamento de Alimentaci\u00f3n y Agricultura de California (CDFA). La certificaci\u00f3n fue concedida a un respetado agricultor de legado <a       href=\"https:\/\/humboldtdryfarmedcannabisalliance.com\/sensiboldt-organics\/\">Productos org\u00e1nicos Sensiboldt<\/a> del condado de Humboldt, y The Highland Canopy en <a       href=\"https:\/\/sonomahillsfarm.com\/\">Granja Sonoma Hills<\/a>una nueva granja de cannabis artesanal de primera calidad y jard\u00edn culinario situado en el condado de Sonoma.\u00a0<\/p>\n<p>Las normas, el proceso de certificaci\u00f3n y la reglamentaci\u00f3n de OCal, el primer programa de certificaci\u00f3n de cannabis de este tipo en EE.UU., reflejan casi exactamente los del Programa Nacional de Productos Ecol\u00f3gicos (NOP) del USDA, lo que garantiza a los consumidores que los productos de cannabis que llevan el sello OCal han cumplido las normas coherentes y uniformes comparables a las del NOP.\u00a0<\/p>\n<p>\"Estamos encantados de certificar a Sensiboldt Organics y Sonoma Hills Farm como los primeros en cumplir las normas OCal de California\", dijo la directora general de CCOF, Kelly Damewood. \"La certificaci\u00f3n OCal del cannabis celebra la integridad y la transparencia de los cultivadores de cannabis que utilizan pr\u00e1cticas org\u00e1nicas establecidas desde hace tiempo, como el cultivo de suelos sanos, el fomento de la biodiversidad y la eliminaci\u00f3n del uso de pesticidas cancer\u00edgenos\". Como todos los cultivos agr\u00edcolas de California, el cannabis puede, y debe, cultivarse con pr\u00e1cticas de producci\u00f3n que protejan la tierra y nuestras comunidades. Aplaudimos a ambas granjas por predicar con el ejemplo\".<\/p>\n<p>Con sus operaciones dirigidas por <a       href=\"https:\/\/sonomahillsfarm.com\/people\/\">Aaron Keefer<\/a>, <a       href=\"https:\/\/sonomahillsfarm.com\/\">Granja Sonoma Hills<\/a> (SHF) cultiva cannabis artesanal de primera calidad, libre de pesticidas y cultivado de forma sostenible bajo el sol de California. La misi\u00f3n de Keefer y su equipo en Sonoma Hills Farm es unir el cannabis con el rico legado agr\u00edcola de Sonoma introduciendo el cannabis artesanal en el estilo de vida de la granja a la mesa. Adem\u00e1s de cultivar cannabis de primera calidad, la granja cuenta con un rico jard\u00edn culinario con la intenci\u00f3n de mostrar c\u00f3mo el cannabis es sin\u00e9rgico con la agricultura tradicional y puede integrarse en un estilo de vida de la granja a la mesa. Los pastos, verduras y flores de la granja tambi\u00e9n han obtenido recientemente la certificaci\u00f3n org\u00e1nica.<\/p>\n<p>La variedad gen\u00e9tica de Sonoma Hills Farm, dirigida al consumidor de flores sofisticado y experimentado, incluye tanto variedades cl\u00e1sicas como \u00fanicas, cada una de ellas cosechada de forma selectiva en el punto \u00f3ptimo de maduraci\u00f3n de los tricomas, y seleccionada para aquellos que buscan flores con un alto contenido en THC, as\u00ed como perfiles din\u00e1micos de cannabinoides y terpenos sabrosos.<\/p>\n<p>\"Se siente surrealista despu\u00e9s de un viaje de a\u00f1o y medio para establecer algo que nadie ha hecho antes, y nos sentimos honrados de ser certificados como una de las primeras granjas de cannabis 'comparable a org\u00e1nico' en el pa\u00eds\", dijo Aaron Keefer, vicepresidente de cultivo y producci\u00f3n de Sonoma Hills Farm. \"Trabajamos muy duro para cultivar cannabis con los m\u00e1s altos est\u00e1ndares, obtener la mejor expresi\u00f3n de la planta y crear un producto de primera calidad sin compromisos ni atajos. Los consumidores merecen saber c\u00f3mo se cultiva su cannabis y de d\u00f3nde procede, al igual que sus tomates, lechugas y carne de vacuno, y naturalmente de eso trata este programa.\"\u00a0<\/p>\n<p><a       href=\"https:\/\/humboldtdryfarmedcannabisalliance.com\/sensiboldt-organics\/\">Productos org\u00e1nicos Sensiboldt<\/a> es la divisi\u00f3n de cannabis de una antigua granja familiar de cultivo de hortalizas y semillas, Eel River Produce en Shively, que es la granja org\u00e1nica certificada por el CCOF que lleva m\u00e1s tiempo en funcionamiento en el condado de Humboldt. Miembro fundador de la <a       href=\"https:\/\/humboldtdryfarmedcannabisalliance.com\/\">Alianza del Cannabis Cultivado en Secano de Humboldt<\/a>El cannabis de la granja se cultiva aplicando los mismos m\u00e9todos biodin\u00e1micos de cultivo en seco utilizados para nutrir su suelo durante m\u00e1s de treinta a\u00f1os. Con un enfoque en la biodiversidad, sus rasgos \u00f3ptimos de cannabis se expresan cuando \"la rica composici\u00f3n del suelo, las ofrendas de la Madre Naturaleza y las pr\u00e1cticas conscientes se alinean.\"<\/p>\n<p>Bill Reynolds, pionero del movimiento de agricultura ecol\u00f3gica, fundador de Eel River Produce y Sensiboldt Organics, ha fallecido recientemente tras dedicar d\u00e9cadas a la agricultura ecol\u00f3gica, a la creaci\u00f3n del movimiento \"de la granja a la mesa\" y al cultivo de semillas ecol\u00f3gicas. Reynolds es un criador de semillas de renombre mundial y un miembro muy querido de la comunidad de agricultores org\u00e1nicos, conocido como un mentor atento con un carisma y un encanto infinitos. Comparti\u00f3 su experiencia con innumerables estudiantes, agricultores ecol\u00f3gicos, criadores de semillas y personal e inspectores del CCOF. En un <a       href=\"https:\/\/ccof.org\/es\/blog\/thank-you-bill-reynolds-and-eel-river-produce\/\">puesto de homenaje por jubilaci\u00f3n el pasado mes de julio de 2020<\/a>, el CCOF expres\u00f3 su agradecimiento a Bill por sus muchas d\u00e9cadas de compromiso.\u00a0<\/p>\n<p>\"Este es un logro monumental para nosotros, la industria del cannabis y los consumidores, y es s\u00f3lo gracias al equipo del CCOF que se comprometi\u00f3 a hacer realidad este hito\", dijo Rosie Reynolds, propietaria y CEO de Sensiboldt Organics. \"Este es uno de los sue\u00f1os de mi padre hecho realidad: cada a\u00f1o, durante la inspecci\u00f3n de CCOF, intentaba persuadir al inspector para que incluyera el cannabis en la lista de nuestros cultivos certificados y siempre le desconcertaba que no fuera una opci\u00f3n, ya que se trata de un cultivo m\u00e1s que utiliza las mismas pr\u00e1cticas agr\u00edcolas. Estamos muy agradecidos de poder referirnos oficialmente a nuestro cannabis artesanal como comparable a org\u00e1nico, y esperamos poder eliminar \"comparable\" en un futuro pr\u00f3ximo, as\u00ed como llevar nuestro cannabis a las masas, mucho m\u00e1s all\u00e1 de los l\u00edmites de nuestro estado.\"<\/p>\n<p>El proceso de OCal implica una solicitud, revisi\u00f3n, inspecci\u00f3n, revisi\u00f3n del cumplimiento de las normas OCal comparables a las org\u00e1nicas y, por \u00faltimo, la certificaci\u00f3n para aquellos que cumplan todas las normas. El reglamento OCal fue dise\u00f1ado para adherirse a la regulaci\u00f3n org\u00e1nica NOP y la orientaci\u00f3n, con peque\u00f1as modificaciones para aclarar los t\u00e9rminos espec\u00edficos de cannabis, apoyar la administraci\u00f3n estatal del nuevo programa, y proporcionar coherencia entre los reglamentos estatales de cannabis.       Aunque OCal es un programa espec\u00edfico del estado de California, el USDA podr\u00eda ofrecer la certificaci\u00f3n org\u00e1nica al cannabis si el cultivo se legalizara a nivel federal.\u00a0<\/p>\n<p>a\u00f1adi\u00f3 Keefer: \"La adopci\u00f3n nacional es s\u00f3lo cuesti\u00f3n de tiempo, y esperamos ser un buen ejemplo para otras granjas de California y de todo Estados Unidos\".<\/p>\n<p>Adem\u00e1s de la certificaci\u00f3n OCal, ambas explotaciones son tambi\u00e9n <a href=\"https:\/\/sunandearth.org\/\">Certificado Sol+Tierra<\/a>, una certificaci\u00f3n sin \u00e1nimo de lucro para el cannabis y el c\u00e1\u00f1amo org\u00e1nicos regenerativos cultivados bajo el sol por peque\u00f1os agricultores familiares.\u00a0<\/p>\n<p><strong>Acerca de Sonoma Hills Farm<\/strong><\/p>\n<p>Sonoma Hills Farm es una intersecci\u00f3n cultural y educativa de peque\u00f1as granjas de cannabis y la agricultura tradicional, el cultivo de cannabis de clase mundial para las personas que son apasionados de la planta, de los consumidores m\u00e1s exigentes a los de la gama alta culinaria y las industrias de la hospitalidad.  Una de las primeras granjas certificadas seg\u00fan las directrices de California para el cannabis certificado \"comparable al org\u00e1nico\" (<a href=\"https:\/\/www.cdfa.ca.gov\/calcannabis\/ocal.html\">OCAL)<\/a>La granja ofrece flores de cannabis de primera calidad cultivadas al sol a socios mayoristas y a los mejores dispensarios minoristas de California a trav\u00e9s de <a href=\"https:\/\/www.nabis.com\/\">Nabis<\/a>as\u00ed como la venta directa al consumidor en lotes limitados de flores preenvasadas. Sonoma Hills Farm es propiedad y est\u00e1 gestionada por <a href=\"https:\/\/big-rock.com\/\">Socios de Big Rock<\/a>Un equipo experimentado con a\u00f1os de experiencia en agricultura, cannabis y hosteler\u00eda. Para m\u00e1s informaci\u00f3n, p\u00f3ngase en contacto con info@sonomahillsfarm.com. Lic. #CDFA: CCL20-000520.       Siga a Sonoma Hills Farm en <a       href=\"https:\/\/www.instagram.com\/sonomahillsfarm\/\">Instagram<\/a>, <a       href=\"https:\/\/www.facebook.com\/sonomahillsfarm\/\">Facebook<\/a>y tambi\u00e9n les <a       href=\"https:\/\/www.linkedin.com\/company\/sonoma-hills-farm\/\">LinkedIn<\/a>.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<figure class=\"content-image\"><\/figure>","protected":false},"excerpt":{"rendered":"<p>Dos explotaciones de cannabis de California han sido pioneras en ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[113],"class_list":["post-33683","post","type-post","status-publish","format-standard","hentry","category-consumer-education","language-english","consumer_education_topics-american-farmland-sustainability","consumer_education_topics-environment","consumer_education_topics-producer-welfare-health","consumer_education_topics-supply-chain-sustainability","consumer_education_topics-why-organic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Tale of Two Farms Dedicated to the Same Cause - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccof.org\/es\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Tale of Two Farms Dedicated to the Same Cause - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"Two California cannabis farms have pioneered a new milestone in cannabis, and are &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccof.org\/es\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T22:46:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T21:08:20+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"A Tale of Two Farms Dedicated to the Same Cause\",\"datePublished\":\"2021-11-02T22:46:17+00:00\",\"dateModified\":\"2024-04-23T21:08:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/\"},\"wordCount\":1064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Consumer Education\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/\",\"url\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/\",\"name\":\"A Tale of Two Farms Dedicated to the Same Cause - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2021-11-02T22:46:17+00:00\",\"dateModified\":\"2024-04-23T21:08:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/a-tale-of-two-farms-dedicated-to-the-same-cause\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Tale of Two Farms Dedicated to the Same Cause\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia de dos granjas dedicadas a la misma causa - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccof.org\/es\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/","og_locale":"es_MX","og_type":"article","og_title":"A Tale of Two Farms Dedicated to the Same Cause - CCOF.org","og_description":"Two California cannabis farms have pioneered a new milestone in cannabis, and are &hellip;","og_url":"https:\/\/ccof.org\/es\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2021-11-02T22:46:17+00:00","article_modified_time":"2024-04-23T21:08:20+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/#article","isPartOf":{"@id":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"A Tale of Two Farms Dedicated to the Same Cause","datePublished":"2021-11-02T22:46:17+00:00","dateModified":"2024-04-23T21:08:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/"},"wordCount":1064,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Consumer Education"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/","url":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/","name":"Historia de dos granjas dedicadas a la misma causa - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2021-11-02T22:46:17+00:00","dateModified":"2024-04-23T21:08:20+00:00","breadcrumb":{"@id":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ccof.org\/news\/a-tale-of-two-farms-dedicated-to-the-same-cause\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"A Tale of Two Farms Dedicated to the Same Cause"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/33683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/comments?post=33683"}],"version-history":[{"count":2,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/33683\/revisions"}],"predecessor-version":[{"id":36359,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/posts\/33683\/revisions\/36359"}],"wp:attachment":[{"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/media?parent=33683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccof.org\/es\/wp-json\/wp\/v2\/categories?post=33683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}